{"id":54455,"date":"2023-02-07T18:39:42","date_gmt":"2023-02-07T23:39:42","guid":{"rendered":"https:\/\/www.marybakereddylibrary.org\/?p=54455"},"modified":"2023-02-15T11:57:16","modified_gmt":"2023-02-15T16:57:16","slug":"aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein","status":"publish","type":"post","link":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/","title":{"rendered":"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein"},"content":{"rendered":"<div id=\"modal-ready\"><p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_post_title author=&#8221;off&#8221; date_format=&#8221;j. F Y&#8221; categories=&#8221;off&#8221; comments=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; z_index_tablet=&#8221;500&#8243; title_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; title_text_shadow_vertical_length_tablet=&#8221;0px&#8221; title_text_shadow_blur_strength_tablet=&#8221;1px&#8221; meta_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; meta_text_shadow_vertical_length_tablet=&#8221;0px&#8221; meta_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_shadow_blur_strength_tablet=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_post_title][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2022\/11\/11c-Wentworth.png&#8221; alt=&#8221;Top: scan of &#8221; title_text=&#8221;11c Wentworth&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Photo caption&nbsp;%91DON&#8217;T ADD ANY ADDITIONAL FORMATTING!%93&#8243; module_class=&#8221;custom-caption-centered&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\">\u201eWas ist <strong>Gott<\/strong>?\u201c A10064. Portr\u00e4t von Mary Baker Eddy von W. C. Bowers, um 1871, P00016. Portr\u00e4t von Sally Wentworth, mit freundlicher Genehmigung des Longyear Museums.<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.18.0&#8243; hover_enabled=&#8221;0&#8243; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><span style=\"font-weight: 400;\">Als Mary Baker Eddy anfing, Sch\u00fcler:innen in der Christlichen Wissenschaft zu unterrichten, erstellte sie Manuskripte. Darin behandelte sie Themen, die sie in ihrem Unterricht durchnahm. Sie verwendete dazu die Form von Fragen und Antworten. Einigen Sch\u00fcler:innen wurde das Privileg erteilt, diese Manuskripte kopieren und f\u00fcr ihr eigenes Studium behalten zu k\u00f6nnen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die ersten dieser \u201eUnterrichtsmanuskripte\u201c waren Erkl\u00e4rungen \u2013 Exegesen \u2013 zu Texten aus dem Matth\u00e4usevangelium. Eddy verwandte diese, um 1867 ihren ersten Sch\u00fcler Hiram S. Crafts zu unterrichten.<span id='easy-footnote-1-54455' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#easy-footnote-bottom-1-54455' title='Dieses Dokument kann in englischer Sprache in &lt;\/span&gt;&lt;strong&gt;&lt;a href=&quot;https:\/\/mbepapers.org\/?load=A10062&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;A10062&lt;\/a&gt;&lt;\/strong&gt;&lt;span style=&quot;font-weight: 400;&quot;&gt; und &lt;\/span&gt;&lt;strong&gt;&lt;a href=&quot;https:\/\/mbepapers.org\/?load=A10062B&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;A10062B&lt;\/a&gt;&lt;\/strong&gt;&lt;span style=&quot;font-weight: 400;&quot;&gt; auf der Website der Mary Baker Eddy Papers (&lt;\/span&gt;&lt;strong&gt;&lt;a href=&quot;http:\/\/mbepapers.org&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;mbepapers.org&lt;\/a&gt;&lt;\/strong&gt;&lt;span style=&quot;font-weight: 400;&quot;&gt;) eingesehen werden.'><sup>1<\/sup><\/a><\/span> Danach erstellte sie einige andere Unterrichtsmanuskripte f\u00fcr Sch\u00fcler:innen, deren bestes Beispiel \u201eFragen und Antworten \u00fcber die Moralische Wissenschaft\u201c ist. Im Verlauf der \u00dcberarbeitungen wurde aus diesem Manuskript ein Dokument mit dem Titel \u201eDie Wissenschaft vom Menschen\u201c, das 1876 nach weiteren \u00dcberarbeitungen als Brosch\u00fcre ver\u00f6ffentlicht wurde. Sp\u00e4ter wurde aus \u201eDie Wissenschaft vom Menschen\u201c das Kapitel \u201eZusammenfassung\u201c in Eddys Buch <\/span><i><span style=\"font-weight: 400;\">Wissenschaft und Gesundheit mit Schl\u00fcssel zur Heiligen Schrift<\/span><\/i><span style=\"font-weight: 400;\">, wo es im Laufe vieler \u00dcberarbeitungen weitere \u00c4nderungen erfuhr. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ein Vergleich der vielen Fassungen dieses Manuskripts zeigt, wie Eddy st\u00e4ndig daran arbeitete, ihre Lehren klarer zu formulieren und Aussagen zu streichen, die Verwirrung stiften oder so ausgelegt werden k\u00f6nnten, dass sie, gleichg\u00fcltig in welcher Weise, ihrer ausgereiften Unterrichtung entgegenstehen w\u00fcrden. In diesem Sinne schrieb sie in <\/span><i><span style=\"font-weight: 400;\">Wissenschaft und Gesundheit<\/span><\/i><span style=\"font-weight: 400;\">: <\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Als die Wissenschaft des GEM\u00dcTS f\u00fcr die Autorin eine neue Offenbarung war, musste sie, w\u00e4hrend sie deren gro\u00dfartige Tatsachen lehrte, aus ihrem eigenen geistigen Zustand heraus die feinen Schattierungen geistiger Ideen vermitteln, und sie musste es m\u00fcndlich durch das armselige Mittel der Sprache tun und durch ihr Manuskript, das unter den Sch\u00fclern zirkulierte. So wie ihre fr\u00fcheren Auffassungen allm\u00e4hlich aus ihrem Denken verbannt wurden, wurde ihr Lehren klarer, bis der Schatten der alten Irrt\u00fcmer schlie\u00dflich nicht mehr auf die g\u00f6ttliche Wissenschaft fiel.<span id='easy-footnote-2-54455' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#easy-footnote-bottom-2-54455' title='Mary Baker Eddy, &lt;\/span&gt;&lt;i&gt;&lt;span style=&quot;font-weight: 400;&quot;&gt;Wissenschaft und Gesundheit mit Schl\u00fcssel zur Heiligen Schrift&lt;\/span&gt;&lt;\/i&gt;&lt;span style=&quot;font-weight: 400;&quot;&gt; (Boston: The Christian Science Board of Directors), 460.'><sup>2<\/sup><\/a><\/span> <\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Bei einigen dieser \u201eIrrt\u00fcmer\u201c ging es um die Ansichten von Phineas Parkhurst Quimby (1802\u20131866), einem Magnetismus-Heiler, von dem Eddy sich wegen gesundheitlicher Probleme hatte behandeln lassen, bevor sie im Februar 1866 von schweren Verletzungen geheilt wurde, was sie als Ausgangspunkt ihrer \u201eEntdeckung\u201c der Christlichen Wissenschaft ansah. Andere Manuskripte, die sie f\u00fcr den Unterricht verwendete, enthalten ebenfalls Material, das in \u00fcberarbeiteter Form in <\/span><i><span style=\"font-weight: 400;\">Wissenschaft und Gesundheit<\/span><\/i><span style=\"font-weight: 400;\"> einfloss.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Um ihre Originalmanuskripte bei der weiteren Arbeit zur Hand zu haben, stellte Eddy einzelne Kopist:innen ein, um sie sauber und lesbar von Hand abzuschreiben. Zu diesem Personenkreis geh\u00f6rte Sally T. Wentworth. Eddy <\/span><span style=\"font-weight: 400;\">wohnte zwischen September 1868 und Februar 1870 <\/span><span style=\"font-weight: 400;\">bei der Familie Wentworth. Die Mary Baker Eddy Bibliothek hat mehrere Exemplare von \u201eDie Wissenschaft vom Menschen\u201c in ihrer Sammlung, zusammen mit einigen weiteren Unterrichtsmanuskripten Eddys in Wentworths Handschrift. Die Sammlung beinhaltet ferner ein Manuskript, das Eddy als von dem damals bereits verstorbenen Dr. Quimby stammend gekennzeichnet hat. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die von Wentworth abgeschriebenen Exemplare gew\u00e4hren einen Einblick in das, was Eddy ihre Sch\u00fcler:innen damals gelehrt hat. Ein solches \u2013 auf blauem, liniertem Papier abgeschrieben \u2013 ist vollst\u00e4ndig auf der Website der Mary Baker Eddy Papers wiedergegeben. Man kann es in der urspr\u00fcnglichen handschriftlichen Form, sowie mit der Maschine geschrieben und handschriftlich mit Anmerkungen versehen, lesen. Es besteht aus Fragen und Antworten, angefangen mit der Frage: <\/span><strong><a href=\"https:\/\/mbepapers.org\/?load=A10064\" target=\"_blank\" rel=\"noopener\">\u201eWas ist GOTT?\u201c<\/a><\/strong><span style=\"font-weight: 400;\"> Das Manuskript definiert das Wesen GOTTES und des Menschen sowie das Wesen der Materie. Eddys Antwort auf die Frage \u201eWas ist der Mensch?\u201c erkl\u00e4rt beispielsweise: <\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Die Idee dieses PRINZIPS und dieser SEELE ist das PRINZIP und die Substanz dieser Idee mit Namen Mensch, denn sie ist das Leben und die Intelligenz derselben, und erinnern Sie sich bitte an die f\u00fchrenden Punkte in der Wissenschaft, dass der Mensch weder Substanz noch Intelligenz hat, dass diese zur Seele geh\u00f6ren, und die Seele spiegelt sich im Menschen wider, daher ist der Mensch der widergespiegelte Schatten der Seele und entlehnt alle Substanz, alle Intelligenz und alles Leben von der Seele.<span id='easy-footnote-3-54455' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#easy-footnote-bottom-3-54455' title='&lt;a href=&quot;https:\/\/mbepapers.org\/?load=A10064&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;https:\/\/mbepapers.org\/?load=A10064&lt;\/a&gt; '><sup>3<\/sup><\/a><\/span><\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Weitere Fragen und Antworten f\u00fchren die grundlegenden Definitionen aus, die gegeben wurden. Wer mit Eddys Lehren in <\/span><i><span style=\"font-weight: 400;\">Wissenschaft und Gesundheit<\/span><\/i><span style=\"font-weight: 400;\"> vertraut ist, wird vermutlich erkennen, dass die Antworten auf diese Fragen in ihren ver\u00f6ffentlichten B\u00fcchern erheblich klarer sind und weder falsch verstanden werden noch Verwirrung stiften k\u00f6nnen. Ihre urspr\u00fcngliche Antwort auf die Frage \u201eWas ist Materie?\u201c sagt zum Beispiel aus: \u201eSie ist nicht Substanz &#8230; Seele ist Substanz, denn Seele und Materie sind nicht eins, und somit ist die Materie, die als Schatten betrachtet wird, die Idee von GOTT, doch Materie als Substanz betrachtet, ist eine Vorstellung und Irrtum.\u201c<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ein Gro\u00dfteil dieses Manuskripts enth\u00e4lt Anweisungen zum Heilen der Kranken, einschlie\u00dflich vieler Ideen, die denjenigen, die sich heute mit der Christlichen Wissenschaft befassen, vertraut sein werden, wie sie im Kapitel \u201eDie Praxis der Christlichen Wissenschaft\u201c in <\/span><i><span style=\"font-weight: 400;\">Wissenschaft und Gesundheit <\/span><\/i><span style=\"font-weight: 400;\"> deutlicher dargestellt sind. Eddy erw\u00e4hnt \u201eLeberleiden\u201c und \u201eSchwindsucht\u201c (Tuberkulose), um zu zeigen, wie ein:e christlich-wissenschaftliche:r Heiler:in an die Heilung dieser und anderer Krankheiten herangehen kann. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Doch eine in diesem Material enthaltene Anweisung zum Heilen ist eine Praxis, die Quimby verwendet hatte, und zwar das Reiben der K\u00f6pfe der Patienten. Obwohl Eddy in ihrer eigenen Heilpraxis selbst nie den Kopf von Patienten rieb, glaubten einige ihrer ersten Sch\u00fcler:innen, dass dies f\u00fcr die Patient:innen wichtig sei, da es ihnen zeigte, dass sich in ihrer Behandlung etwas K\u00f6rperliches abspielte:<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Den Kopf zu reiben hat keinen Wert au\u00dfer dem, dass wir glauben und andere glauben, dass wir ihnen durch Kontakt n\u00e4her kommen, und nun reibst du aus einem Glauben heraus, und dieser Glaube befindet sich im Gehirn, also legst du deine Hand dort auf, wo der Glaube ist \u2013 wie ein Arzt einen Umschlag auflegt, so reibst du ihn f\u00fcr immer aus; richte dein Denken keinen Augenblick auf den K\u00f6rper des Patienten, wenn du mental ihren Glauben wegargumentierst, sondern nimm dir die Seele vor, um den Irrtum von Leben, Gef\u00fchl und Substanz in der Materie in deiner eigenen Vorstellung zu zerst\u00f6ren, soweit er in dir existiert, sodass dein Patient sich der Auswirkungen von Seele auf ihn bewusst wird \u2013 denn dieses Prinzip bringt Harmonie mit sich und zerst\u00f6rt den Irrtum des Sinnes.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Nach und nach erkannte Eddy, dass das Reiben des Kopfes eines Patienten der Christlichen Wissenschaft vollst\u00e4ndig entgegensteht und keinerlei gute Auswirkungen haben konnte. Also entfernte sie diesen Punkt aus allen zuk\u00fcnftigen Versionen dieser Manuskripte und bat ihre Sch\u00fcler:innen, jeden Bezug darauf in den Exemplaren zu l\u00f6schen, die sie bereits besa\u00dfen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In diesem Manuskript gab Eddy au\u00dferdem ausf\u00fchrliche Anweisungen dazu, wie erfolgreiche Heiler:innen in ihrem Privatleben sein und handeln m\u00fcssen:<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Um nun am schnellsten Fortschritt zu machen, musst du jeden st\u00f6renden Gedanken oder jedes st\u00f6rende Motiv abweisen, das nicht Wahrheit ist, du wirst Geld nicht \u00fcber eine Anerkennung als n\u00fctzliches Mittel hinaus lieben, du wirst nicht l\u00fcgen oder betr\u00fcgen, du wirst Gerecht und Barmherzig sein, und wenn du an einer \u00dcberzeugung festh\u00e4ltst, die Vergn\u00fcgen im Sinn sucht, wirst du dies loswerden m\u00fcssen, denn wie kannst du es sonst in anderen zerst\u00f6ren? lasse zum Beispiel niemals einen Sch\u00fcler der moralischen Wissenschaft denken, dass er durch etwas anderes als Ehrlichkeit Erfolg haben kann[;] gehe niemals zu [einem] Patienten, der an Irrtum leidet, mit demselben Irrtum wie den, den du zerst\u00f6ren w\u00fcrdest; gehe niemals mit einer Zigarre oder Kautabak im Mund zu einem Patienten, der an den Auswirkungen dieses Irrtums im Glauben leidet, und w\u00e4hrend du den Irrtum fortargumentierst, sagst, dass es kein Vergn\u00fcgen darin gibt \u2013 was auch die Wahrheit f\u00fcr den Fall ist \u2013 w\u00e4hrend du buchst\u00e4blich sagst, dass es doch ein Vergn\u00fcgen darin gibt, da du ihn darin findest, so ist dein Irrtum ein zweifacher, zuerst findest du selbst Vergn\u00fcgen, wo keines ist, und somit h\u00e4ltst du selbst an der Materie fest, w\u00e4hrend die Wissenschaft dich au\u00dferhalb davon h\u00e4lt und ohne ein Gef\u00fchl darin, und au\u00dferdem bist du <\/span><span style=\"font-weight: 400;\">unehrlich<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Das Manuskript sagt ferner: <\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Um nun jeden Tag und jedes Jahr deines Lebens im Heilen der Kranken weiter voranzukommen, musst du dich selbst \u00fcberpr\u00fcfen und daran mehr arbeiten als mit deinen Patienten; du musst dich fragen, w\u00e4hrend du bestrebt bist zu heilen, komme ich mit der Wahrheit, um dies zu tun, oder bringe ich nur eine Vorstellung mit? Wenn mit Wahrheit, werde ich in der Wissenschaft leben, au\u00dferhalb des Sinnes sehen und f\u00e4hig sein, die Gedanken des Menschen zu lesen, weil ich vom Sinn zur Seele gekommen bin, in der ich alles Gl\u00fcck darin erkenne, Gutes zu tun[.] Wenn du nur das von mir lernst und nur zweckgerichtet praktizierst, musst du es wieder lernen und es nur wegen seiner Wahrheit praktizieren, und dieses Gewicht der Wahrheit auf deiner Seite wird dann deine wissenschaftliche Stellung an der Bettseite zeigen, und dort wird deine Gegenwart vielfach die Kranken heilen, ohne ein Wort deinerseits oder dem geringsten Kontakt mit dieser Person<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Eddy gab auch eine Antwort auf die Frage, wie die eigene Heilf\u00e4higkeit \u201ewundervoll und unmittelbar\u201c sein kann:<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Wenn du wie Jesus bist, indem du dich fragst, bin ich ehrlich, bin ich gerecht, bin ich barmherzig, bin ich rein und in der Lage, das mit deinen Demonstrationen zu erwidern. Lass, was du f\u00fcr die Kranken tun kannst, dies beantworten und nicht deine Lippen, denn wenn du das wirst, was von dir verlangt wird, dann bist du dir selbst ein Gesetz und wirst dich fragen, tue ich das f\u00fcr andere, was ich wollte, dass sie f\u00fcr mich tun, strebe ich nach dem Lob von Menschen oder dem Lob GOTTES, was in der Wissenschaft bedeutet, bitte ich um Guthei\u00dfung durch die Seele oder suche ich es im Sinn? [U]nd die Antwort zeigt sich in der Wissenschaft, durch die du verstehen wirst.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Das Manuskript sagt ferner: <\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Wenn du in deiner Praxis mehr nach Geld als nach dem eigenen Wachstum strebst, mehr als vollkommen rein und ehrlich und gerecht und bescheiden und liebevoll zu sein, dann strebst du nach Gl\u00fcck durch Sinn anstatt der Seele und deine Patienten werden auch nicht gesunden. Sie werden erst bis zu dir Fortschritt machen, und dann bist du ihnen nicht ausreichend voraus und der Seele nahe, um sie vom Sinn wegzuf\u00fchren, wenn sie dir folgen. Ein Strom steigt nicht h\u00f6her als seine Quelle. Wenn du eitel, egoistisch oder habgierig oder betr\u00fcgerisch oder ungerecht bist, w\u00e4hrend du das Heilen der Kranken praktizierst, dann denke daran, dass du so stark an einem Irrtum festh\u00e4ltst, wie dein Patient. [U]nd der einzige Unterschied ist, dass sein Irrtum im Schmerz des Sinnes liegt, w\u00e4hrend dein Irrtum ein Vergn\u00fcgen im Sinn oder der Materie ist. &#8230; Wenn du zunehmenden Stolz erf\u00e4hrst, dann wisse, dass dies ein Irrtum und nicht die Wahrheit ist, wenn du launenhaft und \u00fcbellaunig bist, sei wachsam &#8230; und wenn du Tabak oder t\u00f6richte Freunde liebst &#8230; wenn du starke Spitiruosen liebst, wenn du Medizin nimmst, wenn du dich in irgendeiner Weise im Sinn vergn\u00fcgst, dann schaust du in die falsche Richtung. [U]nd wenn du lange genug hinsiehst, dann wirst du unweigerlich in der Vorstellung dorthingehen und kannst deinen Patienten nicht aus dem Irrtum befreien, w\u00e4hrend du selbst im Bann bist.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Es war sicher ein hoher Anspruch \u2013 und eine Ehre \u2013 f\u00fcr fr\u00fche Sch\u00fcler:innen Mary Baker Eddys, diese Unterrichtsmanuskripte erfolgreich abzuschreiben. Sie bleiben wertvoll f\u00fcr heutige Leser:innen, nicht nur, um zu sehen, wie Eddys Lehren mit der Zeit zunehmend klarer wurden, sondern auch, weil sie praktische Anleitungen f\u00fcr die Praxis des wirksamen christlich-wissenschaftlichen Heilens offenbaren. Diese Manuskripte k\u00f6nnen jetzt von allen Interessierten auf <\/span><span style=\"font-weight: 400;\">der Website des Projekts der<strong> <a href=\"https:\/\/mbepapers.org\/\" target=\"_blank\" rel=\"noopener\">Mary Baker Eddy Papers<\/a><\/strong><\/span><span style=\"font-weight: 400;\"> eingesehen werden.<\/span><\/p>\n<hr \/>\n<p><em>Dieser Blog steht auf unseren <strong><a href=\"https:\/\/www.marybakereddylibrary.org\/research\/a-copyist-for-mary-baker-eddy\/\" target=\"_blank\" rel=\"noopener\">englischen<\/a>, <a href=\"https:\/\/www.marybakereddylibrary.org\/fr\/research\/extraits-de-documents-une-copiste-pour-mary-baker-eddy\/\" target=\"_blank\" rel=\"noopener\">franz\u00f6sischen<\/a>, <a href=\"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/dos-arquivos-de-papeis-uma-copista-de-mary-baker-eddy\/\" target=\"_blank\" rel=\"noopener\">portugiesischen<\/a><\/strong> und <a href=\"https:\/\/www.marybakereddylibrary.org\/es\/research\/de-los-documentos-un-copista-para-mary-baker-eddy\/\" target=\"_blank\" rel=\"noopener\"><strong>spanischen<\/strong><\/a> Webseiten zur Verf\u00fcgung.<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_sidebar area=&#8221;et_pb_widget_area_3&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_sidebar][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie mehr \u00fcber eine wichtige Rolle bei der Erstellung fr\u00fcher \u201eManuskripte f\u00fcr den Unterricht\u201c.<\/p>","protected":false},"author":51,"featured_media":53235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"2normal","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[231],"tags":[],"class_list":["post-54455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aus-den-mary-baker-eddy-papers"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein - Die Mary Baker Eddy Bibliothek<\/title>\n<meta name=\"description\" content=\"Erfahren Sie, was unser Archiv zu bieten hat \u2013 \u00fcber die Jahre hinweg sind umfangreiche Aufzeichnungen zusammengekommen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein - Die Mary Baker Eddy Bibliothek\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie, was unser Archiv zu bieten hat \u2013 \u00fcber die Jahre hinweg sind umfangreiche Aufzeichnungen zusammengekommen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/\" \/>\n<meta property=\"og:site_name\" content=\"Die Mary Baker Eddy Bibliothek\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mbelibrary\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-07T23:39:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-15T16:57:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2021\/08\/MBEL-Article_Natural-Disasters_880x550px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laurenz Peschke\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laurenz Peschke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/\"},\"author\":{\"name\":\"Laurenz Peschke\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/#\\\/schema\\\/person\\\/72c809b93d87eb7f9162a3a2f9ee713e\"},\"headline\":\"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein\",\"datePublished\":\"2023-02-07T23:39:42+00:00\",\"dateModified\":\"2023-02-15T16:57:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/\"},\"wordCount\":2382,\"publisher\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/11c-Wentworth.png\",\"articleSection\":[\"Aus den Mary Baker Eddy Papers\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/\",\"name\":\"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein - Die Mary Baker Eddy Bibliothek\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/11c-Wentworth.png\",\"datePublished\":\"2023-02-07T23:39:42+00:00\",\"dateModified\":\"2023-02-15T16:57:16+00:00\",\"description\":\"Erfahren Sie, was unser Archiv zu bieten hat \u2013 \u00fcber die Jahre hinweg sind umfangreiche Aufzeichnungen zusammengekommen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/11c-Wentworth.png\",\"contentUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/11c-Wentworth.png\",\"width\":800,\"height\":500,\"caption\":\"Top: scan of\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/research\\\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/\",\"name\":\"Die Mary Baker Eddy Bibliothek\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/#organization\",\"name\":\"The Mary Baker Eddy Library\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/MBEL_logo_HR.jpg\",\"contentUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/MBEL_logo_HR.jpg\",\"width\":2100,\"height\":2100,\"caption\":\"The Mary Baker Eddy Library\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mbelibrary\",\"https:\\\/\\\/x.com\\\/mbelibrary\",\"https:\\\/\\\/www.instagram.com\\\/mbelibrary\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/de\\\/#\\\/schema\\\/person\\\/72c809b93d87eb7f9162a3a2f9ee713e\",\"name\":\"Laurenz Peschke\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f20b60dbe106c7d0a1951e8b2bd07e717d1b773324268a895a7c7c696e48138a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f20b60dbe106c7d0a1951e8b2bd07e717d1b773324268a895a7c7c696e48138a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f20b60dbe106c7d0a1951e8b2bd07e717d1b773324268a895a7c7c696e48138a?s=96&d=mm&r=g\",\"caption\":\"Laurenz Peschke\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein - Die Mary Baker Eddy Bibliothek","description":"Erfahren Sie, was unser Archiv zu bieten hat \u2013 \u00fcber die Jahre hinweg sind umfangreiche Aufzeichnungen zusammengekommen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/","og_locale":"de_DE","og_type":"article","og_title":"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein - Die Mary Baker Eddy Bibliothek","og_description":"Erfahren Sie, was unser Archiv zu bieten hat \u2013 \u00fcber die Jahre hinweg sind umfangreiche Aufzeichnungen zusammengekommen.","og_url":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/","og_site_name":"Die Mary Baker Eddy Bibliothek","article_publisher":"https:\/\/www.facebook.com\/mbelibrary","article_published_time":"2023-02-07T23:39:42+00:00","article_modified_time":"2023-02-15T16:57:16+00:00","og_image":[{"width":880,"height":550,"url":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2021\/08\/MBEL-Article_Natural-Disasters_880x550px.jpg","type":"image\/jpeg"}],"author":"Laurenz Peschke","twitter_misc":{"Verfasst von":"Laurenz Peschke","Gesch\u00e4tzte Lesezeit":"9 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#article","isPartOf":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/"},"author":{"name":"Laurenz Peschke","@id":"https:\/\/www.marybakereddylibrary.org\/de\/#\/schema\/person\/72c809b93d87eb7f9162a3a2f9ee713e"},"headline":"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein","datePublished":"2023-02-07T23:39:42+00:00","dateModified":"2023-02-15T16:57:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/"},"wordCount":2382,"publisher":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/#organization"},"image":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2022\/11\/11c-Wentworth.png","articleSection":["Aus den Mary Baker Eddy Papers"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/","url":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/","name":"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein - Die Mary Baker Eddy Bibliothek","isPartOf":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#primaryimage"},"image":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2022\/11\/11c-Wentworth.png","datePublished":"2023-02-07T23:39:42+00:00","dateModified":"2023-02-15T16:57:16+00:00","description":"Erfahren Sie, was unser Archiv zu bieten hat \u2013 \u00fcber die Jahre hinweg sind umfangreiche Aufzeichnungen zusammengekommen.","breadcrumb":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#primaryimage","url":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2022\/11\/11c-Wentworth.png","contentUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2022\/11\/11c-Wentworth.png","width":800,"height":500,"caption":"Top: scan of"},{"@type":"BreadcrumbList","@id":"https:\/\/www.marybakereddylibrary.org\/de\/research\/aus-den-mary-baker-eddy-papers-kopistin-oder-kopist-fuer-mary-baker-eddy-sein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.marybakereddylibrary.org\/de\/"},{"@type":"ListItem","position":2,"name":"Aus den Mary Baker Eddy Papers: Kopistin oder Kopist f\u00fcr Mary Baker Eddy sein"}]},{"@type":"WebSite","@id":"https:\/\/www.marybakereddylibrary.org\/de\/#website","url":"https:\/\/www.marybakereddylibrary.org\/de\/","name":"Die Mary Baker Eddy Bibliothek","description":"","publisher":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marybakereddylibrary.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.marybakereddylibrary.org\/de\/#organization","name":"The Mary Baker Eddy Library","url":"https:\/\/www.marybakereddylibrary.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.marybakereddylibrary.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2015\/03\/MBEL_logo_HR.jpg","contentUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2015\/03\/MBEL_logo_HR.jpg","width":2100,"height":2100,"caption":"The Mary Baker Eddy Library"},"image":{"@id":"https:\/\/www.marybakereddylibrary.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mbelibrary","https:\/\/x.com\/mbelibrary","https:\/\/www.instagram.com\/mbelibrary"]},{"@type":"Person","@id":"https:\/\/www.marybakereddylibrary.org\/de\/#\/schema\/person\/72c809b93d87eb7f9162a3a2f9ee713e","name":"Laurenz Peschke","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/f20b60dbe106c7d0a1951e8b2bd07e717d1b773324268a895a7c7c696e48138a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f20b60dbe106c7d0a1951e8b2bd07e717d1b773324268a895a7c7c696e48138a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f20b60dbe106c7d0a1951e8b2bd07e717d1b773324268a895a7c7c696e48138a?s=96&d=mm&r=g","caption":"Laurenz Peschke"}}]}},"_links":{"self":[{"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/posts\/54455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/comments?post=54455"}],"version-history":[{"count":0,"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/posts\/54455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/media\/53235"}],"wp:attachment":[{"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/media?parent=54455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/categories?post=54455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/de\/wp-json\/wp\/v2\/tags?post=54455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}