{"id":21695,"date":"2018-07-11T15:44:04","date_gmt":"2018-07-11T19:44:04","guid":{"rendered":"https:\/\/www.marybakereddylibrary.org\/condiciones-de-uso\/"},"modified":"2022-08-31T16:44:54","modified_gmt":"2022-08-31T20:44:54","slug":"termos-de-uso","status":"publish","type":"page","link":"https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/","title":{"rendered":"Termos de Uso"},"content":{"rendered":"<div id=\"modal-ready\"><p>[et_pb_section bb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; specialty=&#8221;off&#8221; next_background_color=&#8221;#000000&#8243; _builder_version=&#8221;3.7.1&#8243;][et_pb_fullwidth_header title=&#8221;Termos de Uso&#8221; background_layout=&#8221;light&#8221; header_fullscreen=&#8221;off&#8221; header_scroll_down=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; background_color=&#8221;rgba(255, 255, 255, 0)&#8221; _builder_version=&#8221;3.7.1&#8243; max_width_tablet=&#8221;50px&#8221; \/][\/et_pb_section][et_pb_section bb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; prev_background_color=&#8221;#000000&#8243; _builder_version=&#8221;3.7.1&#8243;][et_pb_row background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.7.1&#8243;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text use_border_color=&#8221;off&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.7.1&#8243;]<\/p>\n<p><strong>\u00daltima atualiza\u00e7\u00e3o em 9 de setembro de 2016<\/strong><\/p>\n<p>Seja bem-vindo ao mbelibrary.org e marybakereddypapers.org (ou mbepapers.org) (denominados o \u201cSite\u201d), ambos de propriedade e operados por The Mary Baker Eddy Library (um empreendimento administrado por The First Church of Christ, Scientist) (a\u201cBiblioteca\u201d). Ao usar este Site, voc\u00ea aceita e concorda com estes Termos de Uso (\u201cTermos\u201d) e com a Pol\u00edtica de Privacidade do Site, incorporada nestes Termos por refer\u00eancia. A Biblioteca se reserva o direito de alterar estes Termos a qualquer momento. Voc\u00ea concorda que a comunica\u00e7\u00e3o a respeito das altera\u00e7\u00f5es destes Termos seja feita por meio da publica\u00e7\u00e3o das altera\u00e7\u00f5es nesta p\u00e1gina. As altera\u00e7\u00f5es entrar\u00e3o em vigor 14 (catorze) dias ap\u00f3s a sua publica\u00e7\u00e3o. Voc\u00ea dever\u00e1 ler estes Termos e verificar se h\u00e1 altera\u00e7\u00f5es antes de usar o Site.<\/p>\n<h2>Direitos Autorais e Permiss\u00e3o para Reimpress\u00e3o<\/h2>\n<p>O Site \u00e9 \u00a9 2017 The Mary Baker Eddy Library. Todos os direitos que n\u00e3o sejam expressamente outorgados nestes Termos s\u00e3o reservados.<\/p>\n<p>A Biblioteca desenvolveu, compilou, preparou, revisou, selecionou e organizou o Site usando consider\u00e1vel tempo, esfor\u00e7o e dinheiro, e constitui propriedade intelectual da Biblioteca. O conte\u00fado deste Site, que pode incluir textos, fotografias, imagens, logos, \u00e1udios, v\u00eddeos e software, hist\u00f3ricos e contempor\u00e2neos, bem como a compila\u00e7\u00e3o deste conte\u00fado (\u201cConte\u00fado\u201d), \u00e9 propriedade da Biblioteca e suas afiliadas, ou dos fornecedores deste conte\u00fado [para exce\u00e7\u00f5es, consulte a p\u00e1gina [Permiss\u00f5es e Direitos Autorais]. O Site e o Conte\u00fado s\u00e3o protegidos pelas leis de direitos autorais nos Estados Unidos e em outros pa\u00edses, e podem tamb\u00e9m ser protegidos pelas leis e normas relacionadas \u00e0 propriedade intelectual, a respeito de banco de dados, privacidade, marcas registradas, e outras. A Biblioteca poder\u00e1 atualizar ou alterar o Site ou seu Conte\u00fado a qualquer momento, sem aviso pr\u00e9vio.<\/p>\n<p>A Biblioteca concede ao usu\u00e1rio o direito de visualizar o Conte\u00fado e, em alguns casos, imprimir ou baixar o Conte\u00fado, caso a funcionalidade do Site o permita, exclusivamente para uso pessoal, n\u00e3o comercial. N\u00e3o \u00e9 permitido vender, publicar, distribuir ou reproduzir em quantidade nenhum Conte\u00fado deste Site, sem a permiss\u00e3o expressa por escrito da Biblioteca (o que inclui, sem limites, postagens em sites ou p\u00e1ginas de m\u00eddia social). N\u00e3o \u00e9 permitido alterar o Conte\u00fado nem remover sinais de marca registrada, direitos autorais, ou qualquer outro aviso, das c\u00f3pias feitas do Conte\u00fado. Voc\u00ea reconhece que n\u00e3o possui nenhum direito de propriedade ao fazer download ou usar o Conte\u00fado.<\/p>\n<p>As fotografias creditadas a terceiros (como a Thinkstock, Getty Images, ou outras bibliotecas e museus), s\u00e3o propriedade de cada fornecedor. Entre em contato diretamente com o fornecedor para solicitar permiss\u00e3o de uso dos materiais de propriedade dele.<\/p>\n<p>Para obter a permiss\u00e3o de uso das obras de Mary Baker Eddy ou qualquer outro Conte\u00fado, ou para saber mais sobre a hist\u00f3ria dos direitos autorais dos materiais encontrados em mbepapers.org, consulte a p\u00e1gina [Permiss\u00f5es e Direitos Autorais]. Para solicitar permiss\u00e3o para reproduzir qualquer outro Conte\u00fado protegido por direitos autorais constante na Biblioteca, ou para enviar perguntas gerais sobre a pol\u00edtica de reimpress\u00e3o deste Site, envie um e-mail ou entre em contato:<\/p>\n<p>The Mary Baker Eddy Library<br \/>\n200 Massachusetts Avenue, P02-10<br \/>\nBoston, MA 02115<br \/>\nTelefone: +1 617&nbsp;450 7206 [somente em ingl\u00eas]<br \/>\nFax: +1 617&nbsp;450 7048<br \/>\nE-mail: librarymail@mbelibrary.org<\/p>\n<h2>Postagens e Envio de Outro Conte\u00fado<\/h2>\n<p>Caso voc\u00ea envie declara\u00e7\u00f5es, perguntas ou coment\u00e1rios ao Site, estar\u00e1 cedendo \u00e0 Biblioteca e suas afiliadas o direito n\u00e3o-exclusivo, em \u00e2mbito mundial, isento do pagamento de direitos autorais, em car\u00e1ter perp\u00e9tuo, irrevog\u00e1vel e totalmente sublicenci\u00e1vel de reproduzir, distribuir, apresentar, exibir, alterar, traduzir e criar obras derivadas dessas declara\u00e7\u00f5es, perguntas ou coment\u00e1rios, no todo ou em parte, em qualquer m\u00eddia, hoje conhecida ou que venha a ser desenvolvida, com ou sem atribui\u00e7\u00e3o de autoria. Voc\u00ea tamb\u00e9m garante que o material enviado n\u00e3o viola os direitos de terceiros.<\/p>\n<p>A Biblioteca poder\u00e1 publicar as declara\u00e7\u00f5es, perguntas ou coment\u00e1rios a seu exclusivo crit\u00e9rio. N\u00e3o envie nenhum coment\u00e1rio que seja de natureza comercial, que viole direitos autorais ou outros direitos, ou que seja obsceno, difamat\u00f3rio ou depreciativo de outras pessoas.<\/p>\n<h2>Notifica\u00e7\u00e3o e procedimento para reclama\u00e7\u00f5es sobre viola\u00e7\u00e3o de direitos autorais<\/h2>\n<p>Caso voc\u00ea acredite que este Site esteja infringindo os seus direitos autorais, a Biblioteca tomar\u00e1 as medidas adequadas de acordo com a Lei dos Direitos Autorais do Mil\u00eanio Digital (Digital Millennium Copyright Act), T\u00edtulo 17, C\u00f3digo dos Estados Unidos, Se\u00e7\u00e3o 512(c)(2) (\u201cDMCA\u201d). Segundo a DMCA, uma notifica\u00e7\u00e3o por escrito da alegada viola\u00e7\u00e3o de direitos autorais poder\u00e1 ou dever\u00e1 ser enviada ao Agente Designado deste Site, conforme abaixo:<\/p>\n<p>Provedor do servi\u00e7o: The First Church of Christ, Scientst \/The Mary Baker Eddy Library<br \/>\nNome do agente designado para receber a notifica\u00e7\u00e3o da alegada viola\u00e7\u00e3o: Ed Blomquist<br \/>\nEndere\u00e7o completo do agente designado a quem a notifica\u00e7\u00e3o dever\u00e1 ser enviada:<br \/>\n210 Massachusetts Avenue, P03-10, Boston, MA 02115<br \/>\nN\u00famero do Telefone do Agente Designado: +1 617&nbsp;450 2000<br \/>\nE-mail do agente designado: copyright@csps.com<\/p>\n<p>Para ter validade, a Notifica\u00e7\u00e3o dever\u00e1 incluir o seguinte:<\/p>\n<ol>\n<li>Uma assinatura f\u00edsica ou eletr\u00f4nica da pessoa autorizada a agir em nome do propriet\u00e1rio de um direito exclusivo que supostamente tenha sido violado.<\/li>\n<li>A identifica\u00e7\u00e3o da obra cujos direitos autorais tenham sido supostamente violados ou, no caso de v\u00e1rias obras protegidas por direitos autorais em um \u00fanico site estarem inclu\u00eddas em uma \u00fanica notifica\u00e7\u00e3o, uma lista representativa dessas obras no site.<\/li>\n<li>A identifica\u00e7\u00e3o do material que supostamente esteja violando os direitos autorais ou que seja o objeto da atividade infratora e que dever\u00e1 ser removido ou ter o correspondente acesso desabilitado, bem como informa\u00e7\u00f5es razoavelmente suficientes que permitam ao provedor do servi\u00e7o localizar o material.<\/li>\n<li>Informa\u00e7\u00f5es razoavelmente suficientes que permitam ao provedor do servi\u00e7o entrar em contato com a parte reclamante, como endere\u00e7o, n\u00famero de telefone e, se houver, um e-mail por meio do qual a parte reclamante poder\u00e1 ser contatada.<\/li>\n<li>Uma declara\u00e7\u00e3o de que a parte reclamante acredita, de boa f\u00e9, que o uso do material na forma alegada n\u00e3o est\u00e1 autorizado pelo propriet\u00e1rio dos direitos autorais, seu agente, ou pela lei.<\/li>\n<li>Uma declara\u00e7\u00e3o de que as informa\u00e7\u00f5es contidas na notifica\u00e7\u00e3o s\u00e3o corretas e, sob pena de perj\u00fario, de que a parte reclamante est\u00e1 autorizada a agir em nome do propriet\u00e1rio de um direito exclusivo que supostamente esteja sendo violado.<\/li>\n<\/ol>\n<h2>Marcas Registradas<\/h2>\n<p><span style=\"font-weight: 400;\">O nome e o logotipo dA Biblioteca Mary Baker Eddy s\u00e3o marcas registradas da Diretoria da Ci\u00eancia Crist\u00e3.<\/span> Com exce\u00e7\u00e3o do que \u00e9 permitido por estes Termos, essas e outras marcas registradas, bem como as imagens do Site n\u00e3o poder\u00e3o ser usadas, sem a pr\u00e9via obten\u00e7\u00e3o de permiss\u00e3o por escrito. Todas as outras marcas registradas s\u00e3o propriedade dos respectivos propriet\u00e1rios.<\/p>\n<h2>Natureza internacional e interestadual das comunica\u00e7\u00f5es no Site<\/h2>\n<p>Voc\u00ea reconhece que ao usar o Site, poder\u00e1 estar enviando comunica\u00e7\u00f5es eletr\u00f4nicas por meio das nossas redes de computadores e das redes de computadores de nossos provedores de servi\u00e7o, sendo que partes dessas redes podem estar localizadas em v\u00e1rias jurisdi\u00e7\u00f5es dentro ou fora dos Estados Unidos. Consequentemente, ao concordar com estes Termos, voc\u00ea reconhece que o uso do Site poder\u00e1 resultar em transmiss\u00f5es de dados em n\u00edvel interestadual ou internacional.<\/p>\n<p>Ao reconhecer a natureza global da internet, voc\u00ea concorda em observar todas as leis aplic\u00e1veis concernentes a conduta on-line, conte\u00fado aceit\u00e1vel e transmiss\u00e3o de dados, ao usar o Site.<\/p>\n<h2>N\u00e3o \u00e9 permitido o uso ilegal ou ofensivo<\/h2>\n<p>Como condi\u00e7\u00e3o para o uso do Site, voc\u00ea n\u00e3o usar\u00e1 o Site para qualquer finalidade que seja ilegal ou proibida por estes Termos.<\/p>\n<ul>\n<li>Voc\u00ea n\u00e3o poder\u00e1 compartilhar as senhas de acesso ao Site.<\/li>\n<li>Voc\u00ea n\u00e3o poder\u00e1 usar o Site de nenhuma forma que possa resultar em dano, inutiliza\u00e7\u00e3o, sobrecarga ou preju\u00edzo, nem interferir no uso ou aprecia\u00e7\u00e3o do Site por outras pessoas.<\/li>\n<li>Voc\u00ea n\u00e3o poder\u00e1 obter Conte\u00fado ou outros materiais e dados por quaisquer meios que n\u00e3o sejam intencionalmente disponibilizados pelo Site.<\/li>\n<li>Voc\u00ea concorda em n\u00e3o alterar o Site nem usar vers\u00f5es alteradas do Site.<\/li>\n<li>Voc\u00ea n\u00e3o poder\u00e1 tentar obter acesso n\u00e3o autorizado a qualquer parte do Site, a outras contas, sistemas de computadores ou redes conectadas ao Site, ou interferir no funcionamento adequado do Site.<\/li>\n<li>Voc\u00ea n\u00e3o poder\u00e1 carregar nenhum c\u00f3digo execut\u00e1vel, <em>scripts<\/em> ou outros dados que alterem a fun\u00e7\u00e3o, apresenta\u00e7\u00e3o ou conte\u00fado do Site.<\/li>\n<\/ul>\n<p>Qualquer suspeita de atividade fraudulenta, abusiva ou ilegal poder\u00e1 ser encaminhada \u00e0s autoridades competentes. Essa medida poder\u00e1 ser tomada sem preju\u00edzo de quaisquer outros recursos dispon\u00edveis sob qualquer rito judici\u00e1rio.<\/p>\n<h2>N\u00e3o \u00e9 permitido o uso de publica\u00e7\u00f5es ou derivados<\/h2>\n<p>Voc\u00ea concorda em n\u00e3o se apropriar, acessar, baixar ou extrair total ou parcialmente o Conte\u00fado ou o Site de forma sistem\u00e1tica ou regular, ou criar uma base de dados ou coleta de materiais em qualquer m\u00eddia, compreendendo todo ou apenas uma sec\u00e7\u00e3o do Conte\u00fado, para ulterior reprodu\u00e7\u00e3o, publica\u00e7\u00e3o, distribui\u00e7\u00e3o, ou para fornecer acesso a outros, quer este material coletado esteja no formato eletr\u00f4nico ou impresso. Voc\u00ea concorda em n\u00e3o colocar c\u00f3pias do Conte\u00fado, total ou parcial, em qualquer reposit\u00f3rio institucional, o que seria uma forma de republica\u00e7\u00e3o.<\/p>\n<h2>N\u00e3o \u00e9 permitido o compartilhamento por <em>framing<\/em> ou <em>embedding<\/em><\/h2>\n<p>Voc\u00ea n\u00e3o poder\u00e1 adotar o compartilhamento por <em>framing<\/em> ou <em>embedding<\/em> de p\u00e1ginas ou Conte\u00fado espec\u00edfico encontrado no Site, exceto conforme expressamente permitido ou habilitado pela funcionalidade do Site ou de um de seus sites hospedeiros (como v\u00eddeos hospedados no Vimeo).<\/p>\n<h2>Inclus\u00e3o de links<\/h2>\n<p>A Biblioteca o convida a fornecer o link para a p\u00e1gina principal do Site ou p\u00e1ginas espec\u00edficas, em vez de reproduzir ou republicar o Conte\u00fado do Site. Observe que o Conte\u00fado do Site est\u00e1 sujeito a eventuais altera\u00e7\u00f5es, que podem resultar em links quebrados.<\/p>\n<h2>N\u00e3o \u00e9 permitido adotar o acesso automatizado ou ignorar os cabe\u00e7alhos de exclus\u00e3o de rob\u00f4s<\/h2>\n<p>Voc\u00ea concorda em n\u00e3o usar nenhum rob\u00f4, <em>spider, scraper<\/em> ou outros meios automatizados com o objetivo de ignorar nossos cabe\u00e7alhos de exclus\u00e3o de rob\u00f4s ou outras medidas que possamos adotar para evitar ou restringir o acesso ao Site.<\/p>\n<h2>N\u00e3o \u00e9 permitida a revenda de Conte\u00fado do Site<\/h2>\n<p>Exceto quando expressamente permitido nestes Termos, voc\u00ea n\u00e3o poder\u00e1 reproduzir, distribuir, exibir, apresentar, vender, negociar ou, de qualquer outra forma, explorar para quaisquer fins comerciais, qualquer parte, uso ou acesso ao Site ou ao seu Conte\u00fado.<\/p>\n<h2>Programa\u00e7\u00e3o de \u00e1udio e v\u00eddeo<\/h2>\n<p>A programa\u00e7\u00e3o de \u00e1udio e v\u00eddeo da Biblioteca (\u201cProgramas A\/V\u201d) consiste de <em>webcasts<\/em> ao vivo e material de arquivo, que s\u00e3o disponibilizados por <em>streaming<\/em> gratuito e, em alguns casos, podem ser oferecidos para compartilhamento por <em>embedding<\/em> ou para serem baixados. Quaisquer direitos e usos dos Programas A\/V, os quais n\u00e3o sejam expressamente outorgados nestes Termos ou permitidos pela funcionalidade do Site, s\u00e3o reservados \u00e0 Biblioteca.<\/p>\n<p>Os usos dos Programas A\/V, discriminados abaixo, n\u00e3o s\u00e3o permitidos:<\/p>\n<ul>\n<li>Redistribui\u00e7\u00e3o, edi\u00e7\u00e3o ou altera\u00e7\u00e3o dos Programas A\/V ou dos links correspondentes.<\/li>\n<li>Publica\u00e7\u00e3o de Programas A\/V, exceto por meio da funcionalidade de incorpora\u00e7\u00e3o fornecida, se houver.<\/li>\n<li>Incorpora\u00e7\u00e3o de an\u00fancios ou associa\u00e7\u00e3o de an\u00fancios com Programas A\/V, ou insinua\u00e7\u00e3o de que o Site ou a Biblioteca esteja endossando qualquer produto, servi\u00e7o ou causa de outros grupos.<\/li>\n<li>Inserir uma p\u00e1gina intermedi\u00e1ria ou outro conte\u00fado entre os Programas A\/V e qualquer outro website.<\/li>\n<\/ul>\n<p>A Biblioteca ou seus fornecedores ret\u00eam total propriedade e outros direitos dos Programas A\/V e das logomarcas e marcas registradas associadas. A Biblioteca poder\u00e1 interromper a oferta dos Programas A\/V ou exigir que voc\u00ea pare de usar os Programas A\/V a qualquer momento e por qualquer motivo.<\/p>\n<h2>Encerramento<\/h2>\n<p>A Biblioteca poder\u00e1 a qualquer momento atualizar, alterar ou interromper o Site ou seu Conte\u00fado. As disposi\u00e7\u00f5es dos Termos do Site e Pol\u00edtica de Privacidade continuar\u00e3o em vigor ap\u00f3s o encerramento do Site.<\/p>\n<h2>Sites de terceiros; anunciantes<\/h2>\n<p>O Site poder\u00e1 incluir links ou refer\u00eancias a outros sites ou servi\u00e7os unicamente para a conveni\u00eancia dos usu\u00e1rios (\u201cSites de Refer\u00eancia\u201d). A Biblioteca n\u00e3o endossa os Sites de Refer\u00eancia nem as informa\u00e7\u00f5es, produtos ou servi\u00e7os desses sites, sendo que as suas transa\u00e7\u00f5es com os Sites de Refer\u00eancia ser\u00e3o unicamente entre voc\u00ea e esses sites.<\/p>\n<h2>Limita\u00e7\u00e3o de garantias<\/h2>\n<p>ESTE SITE, SUA OPERA\u00c7\u00c3O E TODAS AS INFORMA\u00c7\u00d5ES, CONTE\u00daDO, MATERIAIS OU PRODUTOS INCLU\u00cdDOS NESTE SITE S\u00c3O FORNECIDOS PELA BIBLIOTECA \u201cTAL COMO SE APRESENTAM\u201d E SEM DECLARA\u00c7\u00d5ES OU GARANTIAS DE QUALQUER TIPO, EXPRESSAS OU IMPL\u00cdCITAS, INCLUINDO, ENTRE OUTRAS, AS GARANTIAS IMPL\u00cdCITAS DE COMERCIABILIDADE, ADEQUA\u00c7\u00c3O PARA UM PROP\u00d3SITO ESPEC\u00cdFICO E N\u00c3O VIOLA\u00c7\u00c3O. A BIBLIOTECA N\u00c3O SE RESPONSIBILIZA POR DANOS DE QUALQUER TIPO DECORRENTES DO USO OU DE ATIVIDADES RELACIONADAS A ESTE SITE, INCLUINDO, ENTRE OUTROS, DANOS DIRETOS, INDIRETOS, EMERGENTES, PUNITIVOS E IMPREVISTOS. DEVIDO AO FATO DE ALGUNS ESTADOS\/JURIDI\u00c7\u00d5ES N\u00c3O PERMITIREM DETERMINADAS ISEN\u00c7\u00d5ES OU LIMITA\u00c7\u00d5ES DE RESPONSABILIDADE, A LIMITA\u00c7\u00c3O ACIMA PODE N\u00c3O SER APLIC\u00c1VEL A VOC\u00ca. A BIBLIOTECA N\u00c3O \u00c9 RESPONS\u00c1VEL, DE NENHUMA FORMA, PELA CONDUTA DOS USU\u00c1RIOS DO SITE NEM PELAS INFORMA\u00c7\u00d5ES TROCADAS ENTRE USU\u00c1RIOS OU POR ELES POSTADAS NO SITE, INCLUINDO ALEGA\u00c7\u00d5ES DE DIFAMA\u00c7\u00c3O, NEM PELA PERDA DE QUALQUER CONTE\u00daDO OU DADOS.<\/p>\n<h2>Indeniza\u00e7\u00e3o<\/h2>\n<p>Voc\u00ea concorda em defender, indenizar e isentar de responsabilidade a Biblioteca, suas entidades afiliadas, diretores, titulares dos cargos oficiais, fiduci\u00e1rios, empregados, contratados, agentes e fornecedores por quaisquer alega\u00e7\u00f5es, perdas, danos, responsabilidades e despesas, incluindo, entre outros, custas e honor\u00e1rios advocat\u00edcios razo\u00e1veis, decorrentes de seu uso ou uso indevido deste Site, por qualquer viola\u00e7\u00e3o ou suposta viola\u00e7\u00e3o de sua parte destes Termos, por qualquer viola\u00e7\u00e3o ou suposta viola\u00e7\u00e3o de sua parte de direitos autorais, marcas registradas, direitos exclusivos ou outros direitos de terceiros, ou por qualquer viola\u00e7\u00e3o de declara\u00e7\u00f5es, garantias e acordos feitos por voc\u00ea segundo estes Termos. A Biblioteca reserva-se o direito, ficando voc\u00ea encarregado das respectivas despesas, de assumir a defesa exclusiva e o controle de qualquer a\u00e7\u00e3o na qual seja exigido que voc\u00ea indenize a Biblioteca, e voc\u00ea concorda em cooperar com a defesa da Biblioteca em rela\u00e7\u00e3o a essas alega\u00e7\u00f5es.<\/p>\n<h2>Isen\u00e7\u00e3o de responsabilidade pessoal<\/h2>\n<p>Nenhum diretor, titular de cargo oficial, fiduci\u00e1rio, empregado ou agente da Biblioteca ou suas afiliadas ser\u00e1 pessoalmente responsabilizado pelo cumprimento ou n\u00e3o cumprimento de qualquer disposi\u00e7\u00e3o destes Termos.<\/p>\n<h2>Legisla\u00e7\u00e3o aplic\u00e1vel<\/h2>\n<p>Todas as limita\u00e7\u00f5es de responsabilidade, pol\u00edticas, termos, condi\u00e7\u00f5es e lit\u00edgios neste instrumento ser\u00e3o regidos de acordo com as leis do Estado de Massachusetts e dos Estados Unidos, independentemente da escolha de princ\u00edpios legais por parte deles.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[et_pb_section bb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; specialty=&#8221;off&#8221; next_background_color=&#8221;#000000&#8243; _builder_version=&#8221;3.7.1&#8243;][et_pb_fullwidth_header title=&#8221;Termos de Uso&#8221; background_layout=&#8221;light&#8221; header_fullscreen=&#8221;off&#8221; header_scroll_down=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; background_color=&#8221;rgba(255, 255, 255, 0)&#8221; _builder_version=&#8221;3.7.1&#8243; max_width_tablet=&#8221;50px&#8221; \/][\/et_pb_section][et_pb_section bb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; prev_background_color=&#8221;#000000&#8243; _builder_version=&#8221;3.7.1&#8243;][et_pb_row background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.7.1&#8243;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text use_border_color=&#8221;off&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.7.1&#8243;] \u00daltima atualiza\u00e7\u00e3o em 9 de setembro de 2016 Seja bem-vindo ao mbelibrary.org e marybakereddypapers.org (ou mbepapers.org) (denominados o \u201cSite\u201d), ambos [&hellip;]<\/p>","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"class_list":["post-21695","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Termos de Uso - A Biblioteca Mary Baker Eddy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Termos de Uso - A Biblioteca Mary Baker Eddy\" \/>\n<meta property=\"og:description\" content=\"[et_pb_section bb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; specialty=&#8221;off&#8221; next_background_color=&#8221;#000000&#8243; _builder_version=&#8221;3.7.1&#8243;][et_pb_fullwidth_header title=&#8221;Termos de Uso&#8221; background_layout=&#8221;light&#8221; header_fullscreen=&#8221;off&#8221; header_scroll_down=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; background_color=&#8221;rgba(255, 255, 255, 0)&#8221; _builder_version=&#8221;3.7.1&#8243; max_width_tablet=&#8221;50px&#8221; \/][\/et_pb_section][et_pb_section bb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; prev_background_color=&#8221;#000000&#8243; _builder_version=&#8221;3.7.1&#8243;][et_pb_row background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.7.1&#8243;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text use_border_color=&#8221;off&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.7.1&#8243;] \u00daltima atualiza\u00e7\u00e3o em 9 de setembro de 2016 Seja bem-vindo ao mbelibrary.org e marybakereddypapers.org (ou mbepapers.org) (denominados o \u201cSite\u201d), ambos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/\" \/>\n<meta property=\"og:site_name\" content=\"A Biblioteca Mary Baker Eddy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mbelibrary\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T20:44:54+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/termos-de-uso\\\/\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/termos-de-uso\\\/\",\"name\":\"Termos de Uso - A Biblioteca Mary Baker Eddy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#website\"},\"datePublished\":\"2018-07-11T19:44:04+00:00\",\"dateModified\":\"2022-08-31T20:44:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/termos-de-uso\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/termos-de-uso\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/termos-de-uso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termos de Uso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/\",\"name\":\"A Biblioteca Mary Baker Eddy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#organization\",\"name\":\"The Mary Baker Eddy Library\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/MBEL_logo_HR.jpg\",\"contentUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/MBEL_logo_HR.jpg\",\"width\":2100,\"height\":2100,\"caption\":\"The Mary Baker Eddy Library\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mbelibrary\",\"https:\\\/\\\/x.com\\\/mbelibrary\",\"https:\\\/\\\/www.instagram.com\\\/mbelibrary\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Termos de Uso - A Biblioteca Mary Baker Eddy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/","og_locale":"pt_BR","og_type":"article","og_title":"Termos de Uso - A Biblioteca Mary Baker Eddy","og_description":"[et_pb_section bb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; specialty=&#8221;off&#8221; next_background_color=&#8221;#000000&#8243; _builder_version=&#8221;3.7.1&#8243;][et_pb_fullwidth_header title=&#8221;Termos de Uso&#8221; background_layout=&#8221;light&#8221; header_fullscreen=&#8221;off&#8221; header_scroll_down=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; background_color=&#8221;rgba(255, 255, 255, 0)&#8221; _builder_version=&#8221;3.7.1&#8243; max_width_tablet=&#8221;50px&#8221; \/][\/et_pb_section][et_pb_section bb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; prev_background_color=&#8221;#000000&#8243; _builder_version=&#8221;3.7.1&#8243;][et_pb_row background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.7.1&#8243;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text use_border_color=&#8221;off&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.7.1&#8243;] \u00daltima atualiza\u00e7\u00e3o em 9 de setembro de 2016 Seja bem-vindo ao mbelibrary.org e marybakereddypapers.org (ou mbepapers.org) (denominados o \u201cSite\u201d), ambos [&hellip;]","og_url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/","og_site_name":"A Biblioteca Mary Baker Eddy","article_publisher":"https:\/\/www.facebook.com\/mbelibrary","article_modified_time":"2022-08-31T20:44:54+00:00","twitter_misc":{"Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/","url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/","name":"Termos de Uso - A Biblioteca Mary Baker Eddy","isPartOf":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#website"},"datePublished":"2018-07-11T19:44:04+00:00","dateModified":"2022-08-31T20:44:54+00:00","breadcrumb":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/termos-de-uso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marybakereddylibrary.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Termos de Uso"}]},{"@type":"WebSite","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#website","url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/","name":"A Biblioteca Mary Baker Eddy","description":"","publisher":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marybakereddylibrary.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#organization","name":"The Mary Baker Eddy Library","url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2015\/03\/MBEL_logo_HR.jpg","contentUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2015\/03\/MBEL_logo_HR.jpg","width":2100,"height":2100,"caption":"The Mary Baker Eddy Library"},"image":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mbelibrary","https:\/\/x.com\/mbelibrary","https:\/\/www.instagram.com\/mbelibrary"]}]}},"_links":{"self":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/pages\/21695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/comments?post=21695"}],"version-history":[{"count":0,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/pages\/21695\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/media?parent=21695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}