{"id":49329,"date":"2022-07-25T15:44:37","date_gmt":"2022-07-25T19:44:37","guid":{"rendered":"https:\/\/www.marybakereddylibrary.org\/escritos\/"},"modified":"2022-09-02T11:39:34","modified_gmt":"2022-09-02T15:39:34","slug":"escritos","status":"publish","type":"page","link":"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/","title":{"rendered":"Escritos"},"content":{"rendered":"<div id=\"modal-ready\"><p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.4.7&#8243; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; custom_margin=&#8221;10px|||&#8221; custom_padding=&#8221;0px|0px|0px|0px&#8221; z_index_tablet=&#8221;0&#8243; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_header title=&#8221;Escritos&#8221; _builder_version=&#8221;4.9.9&#8243; background_repeat=&#8221;repeat-x&#8221; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; z_index_tablet=&#8221;0&#8243; custom_css_main_element=&#8221;height:85px;&#8221; title_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; title_text_shadow_vertical_length_tablet=&#8221;0px&#8221; title_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_text_shadow_blur_strength_tablet=&#8221;1px&#8221; subhead_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; subhead_text_shadow_vertical_length_tablet=&#8221;0px&#8221; subhead_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; button_one_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; button_one_text_shadow_vertical_length_tablet=&#8221;0px&#8221; button_one_text_shadow_blur_strength_tablet=&#8221;1px&#8221; button_two_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; button_two_text_shadow_vertical_length_tablet=&#8221;0px&#8221; button_two_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; box_shadow_horizontal_image_tablet=&#8221;0px&#8221; box_shadow_vertical_image_tablet=&#8221;0px&#8221; box_shadow_blur_image_tablet=&#8221;40px&#8221; box_shadow_spread_image_tablet=&#8221;0px&#8221; box_shadow_horizontal_button_one_tablet=&#8221;0px&#8221; box_shadow_vertical_button_one_tablet=&#8221;0px&#8221; box_shadow_blur_button_one_tablet=&#8221;40px&#8221; box_shadow_spread_button_one_tablet=&#8221;0px&#8221; box_shadow_horizontal_button_two_tablet=&#8221;0px&#8221; box_shadow_vertical_button_two_tablet=&#8221;0px&#8221; box_shadow_blur_button_two_tablet=&#8221;40px&#8221; box_shadow_spread_button_two_tablet=&#8221;0px&#8221; text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_shadow_blur_strength_tablet=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221; button_one_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;on&#8221; button_two_letter_spacing__hover=&#8221;0&#8243; button_two_letter_spacing__hover_enabled=&#8221;on&#8221;][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.22&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2022\/01\/MBEL_MBEWritings_01.jpg&#8221; title_text=&#8221;MBEL_MBEWritings_01&#8243; _builder_version=&#8221;4.9.9&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.14.7&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"font-weight: 400; font-size: 18px; line-height: 1.7em;\">Na juventude, Mary Baker Eddy escreveu em poesia e prosa para revistas e jornais. Depois de descobrir a Ci\u00eancia Crist\u00e3, ela manteve ampla correspond\u00eancia com milhares de pessoas comuns, com l\u00edderes do pensamento na religi\u00e3o, no movimento sufragista e na medicina.<\/p>\n<p style=\"font-weight: 400; font-size: 18px; line-height: 1.7em;\">A publica\u00e7\u00e3o mais importante da Sra. Eddy foi o livro <em>Ci\u00eancia e Sa\u00fade<\/em>. Ela o revisou muitas vezes entre 1875 e sua morte. Ela tamb\u00e9m foi autora de outros 16 t\u00edtulos que est\u00e3o em circula\u00e7\u00e3o ainda hoje.<\/p>\n<p style=\"font-weight: 400; font-size: 18px; line-height: 1.7em;\">Veja a seguir quais s\u00e3o suas obras publicadas:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.14.7&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3><span style=\"font-weight: 600;\"><em>Ci\u00eancia e Sa\u00fade com a Chave das Escrituras<\/em> (1875)*\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esse \u00e9 o livro-texto fundamental da Ci\u00eancia Crist\u00e3. Apresenta o sistema de cura de Mary Baker Eddy, explicando o significado inspirado da B\u00edblia, principalmente as palavras e a\u00e7\u00f5es de Jesus Cristo. \u201cEssa obra \u00e9 o fruto de toda a minha vida\u201d, escreveu ela a um aluno. <em>Ci\u00eancia e Sa\u00fade<\/em> tem 18 cap\u00edtulos, incluindo \u201cA ora\u00e7\u00e3o\u201d, \u201cO matrim\u00f4nio\u201d, \u201cA ci\u00eancia, a teologia e a medicina\u201d e \u201cA pr\u00e1tica da Ci\u00eancia Crist\u00e3\u201d. As \u00faltimas 100 p\u00e1ginas cont\u00eam testemunhos de pessoas que foram curadas pela leitura do livro. Mais de 10 milh\u00f5es de exemplares de <em>Ci\u00eancia e Sa\u00fade<\/em> j\u00e1 foram vendidos, traduzido para 16 idiomas e em braille em ingl\u00eas.<br \/><em>*Tradu\u00e7\u00e3o ao portugu\u00eas publicada por primeira vez em 1963<\/em><br \/><\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>A Cura Crist\u00e3 <\/i>(1886)*\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Aqui, Mary Baker Eddy explica como as curas morais e f\u00edsicas praticadas por Jesus e seus primeiros seguidores s\u00e3o poss\u00edveis atualmente e fazem parte da pr\u00e1tica crist\u00e3 ainda hoje. Ela originalmente o apresentou na forma de serm\u00e3o.<br \/><em>*Tradu\u00e7\u00e3o ao portugu\u00eas publicada por primeira vez em 2010<\/em><\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>A ideia que os homens t\u00eam de Deus \u2014 Seu efeito sobre a sa\u00fade e o Cristianismo <\/i>(1886)*\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Essa publica\u00e7\u00e3o curta examina como uma compreens\u00e3o crescente de Deus pode transformar a sa\u00fade di\u00e1ria de uma pessoa e promover o progresso na demonstra\u00e7\u00e3o do Cristianismo cient\u00edfico. Mary Baker Eddy analisa como a vida das pessoas \u00e9 influenciada por seus pontos de vista a respeito de Deus, e tamb\u00e9m exp\u00f5e o poder das ideias espirituais. Originalmente foi apresentado na forma de serm\u00e3o.<br \/><em>*Tradu\u00e7\u00e3o ao portugu\u00eas publicada por primeira vez em 2010<\/em><br \/><\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>N\u00e3o e Sim <\/i>(1887)*\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esse texto inicialmente serviu como uma resposta de Mary Baker Eddy aos ataques de um pastor local contra a Ci\u00eancia Crist\u00e3. Esclarece os ensinamentos da Ci\u00eancia Crist\u00e3 e mostra como diferem das outras tradi\u00e7\u00f5es crist\u00e3s. Explica como a Ci\u00eancia Crist\u00e3 foi completamente fundamentada no minist\u00e9rio de cura de Jesus.<br \/><em>*Tradu\u00e7\u00e3o ao portugu\u00eas publicada por primeira vez em 1952<\/em><br \/><\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Rudimentos da Ci\u00eancia Divina <\/i>(1887)*\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Essa obra responde a algumas das perguntas mais frequentes a respeito da Ci\u00eancia Crist\u00e3, apresentando uma explica\u00e7\u00e3o concisa de sua teologia. No formato de perguntas e respostas, Mary Baker Eddy apresenta ideias espirituais, respondendo a perguntas como: \u201cA mat\u00e9ria n\u00e3o existe?\u201d; \u201c\u00c9 o homem material, ou \u00e9 ele espiritual?\u201d e \u201cO que devo fazer para demonstrar a Ci\u00eancia Crist\u00e3 na cura dos doentes?\u201d<br \/><em>*Tradu\u00e7\u00e3o ao portugu\u00eas publicada por primeira vez em 1952<\/em><br \/><\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>A Unidade do Bem <\/i>(1887)*\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Nesse livro, Mary Baker Eddy fala sobre a natureza de Deus como o bem supremo e demonstra como essa compreens\u00e3o nos capacita a comprovar a falta de poder do mal. Ela desenvolve esse t\u00f3pico por meio de temas como: \u201cPorventura Deus conhece ou v\u00ea o pecado, a doen\u00e7a e a morte?\u201d, \u201cN\u00e3o existe a morte?\u201d e \u201cA miss\u00e3o do Salvador\u201d.<br \/><em>*Tradu\u00e7\u00e3o ao portugu\u00eas publicada por primeira vez em 2010<\/em><br \/><\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><em>Retrospec\u00e7\u00e3o e Introspec\u00e7\u00e3o<\/em> (1891)*\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Nessa pequena autobiografia, Mary Baker Eddy escreve brevemente sobre sua inf\u00e2ncia e os eventos que a levaram \u00e0 descoberta da Ci\u00eancia Crist\u00e3. Ela explica o que significa seguir e praticar fervorosamente os ensinamentos de Jesus e oferece conselhos que s\u00e3o instrutivos para os atuais estudantes da Ci\u00eancia Crist\u00e3. Ela tamb\u00e9m compartilha ideias sobre como escreveu seu principal trabalho, <em>Ci\u00eancia e Sa\u00fade<\/em> e como estabeleceu A Primeira Igreja de Cristo, Cientista.<br \/><em>*Tradu\u00e7\u00e3o ao portugu\u00eas publicada por primeira vez em 1972<\/em><br \/><\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Christ and Christmas <\/i>[O Cristo e o Natal] (1893)\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esse poema ilustrado de 15 estrofes \u00e9 acompanhado de 11 desenhos feitos a carv\u00e3o e aquarela, criados em uma colabora\u00e7\u00e3o entre Mary Baker Eddy e o artista James Franklin Gilman (1850\u20131929).<\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Manual dA Igreja M\u00e3e <\/i>(1895)*\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esse conciso Estatuto continua a orientar todas as atividades dA Primeira Igreja de Cristo, Cientista, inclusive os cursos sobre a cura pela Ci\u00eancia Crist\u00e3, as confer\u00eancias p\u00fablicas e os cultos da igreja. Est\u00e1 ali delineado o sistema \u00fanico de governo que Mary Baker Eddy estabeleceu para A Igreja M\u00e3e e proporciona orienta\u00e7\u00e3o quanto \u00e0 pr\u00e1tica individual da cura crist\u00e3 como ela a ensinou.<br \/><em>*Tradu\u00e7\u00e3o ao portugu\u00eas publicada por primeira vez em 1968<\/em><br \/><\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Pulpit and Press <\/i>[P\u00falpito e Imprensa] (1895)\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esse livro cont\u00e9m o serm\u00e3o de 1895 de Mary Baker Eddy, proferido na dedica\u00e7\u00e3o dA Primeira Igreja de Cristo, Cientista, al\u00e9m de excertos do culto de dedica\u00e7\u00e3o. Tamb\u00e9m inclui relatos de jornais que narram o nascimento da Ci\u00eancia Crist\u00e3 e mencionam alguns dos progressos do movimento, ao longo de um per\u00edodo de 30 anos, a partir de 1866.<\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Escritos Diversos 1883\u20131896 <\/i>(1896)*\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Essa colet\u00e2nea cont\u00e9m diversos artigos, serm\u00f5es, cartas e poemas fundamentados na experi\u00eancia de Mary Baker Eddy ao p\u00f4r em pr\u00e1tica seu sistema de cura. Os t\u00f3picos incluem cura mental, perd\u00e3o, anjos e casamento. Ela considerava essa colet\u00e2nea como ajuda para compreender melhor <em>Ci\u00eancia e Sa\u00fade,<\/em> a qual inclui dezenas de cartas de pessoas que foram curadas somente pela leitura dessa obra.<br \/><em>*Tradu\u00e7\u00e3o ao portugu\u00eas publicada por primeira vez em 2021<\/em><br \/><\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Christian Science versus Pantheism <\/i>[A Ci\u00eancia Crist\u00e3 frente ao pante\u00edsmo] (1898)\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Essa \u00e9 a mensagem de 1898 de Mary Baker Eddy para a Igreja de Cristo, Cientista. Analisa como o Primeiro Mandamento do Dec\u00e1logo fornece o fundamento da Ci\u00eancia Crist\u00e3 e explica que as cren\u00e7as pante\u00edstas n\u00e3o t\u00eam nenhuma rela\u00e7\u00e3o com o conceito de um Deus universal.<\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Message to The Mother Church for 1900<\/i> [Mensagem \u00c0 Igreja M\u00e3e para 1900] (1900)\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Aqui, Mary Baker Eddy aborda os efeitos fortalecedores e sanadores do Cristianismo genu\u00edno, os quais ocorrem por meio da obedi\u00eancia a Deus e do amor pela humanidade, como Jesus ensinou.<\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Message to The Mother Church for 1901 <\/i>[Mensagem \u00c0 Igreja M\u00e3e para 1901] (1901)\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Essa obra oferece uma percep\u00e7\u00e3o da natureza infinita de Deus; aborda temas como: o Cristo; o Pastor da Igreja de Cristo, Cientista; a medicina; e outros t\u00f3picos relevantes para a pr\u00e1tica da Ci\u00eancia Crist\u00e3.<\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Message to The Mother Church for 1902 <\/i>[Mensagem \u00c0 Igreja M\u00e3e para 1902] (1902)\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Aqui Mary Baker Eddy faz uma profunda an\u00e1lise do Primeiro Mandamento e da natureza de Deus, o Amor infinito, e do mandamento de Jesus que amemos uns aos outros \u2014 todos esses ensinamentos s\u00e3o fundamentais e imperativos para a pr\u00e1tica dessa religi\u00e3o.<\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>Poems <\/i>[Poemas] (1910)\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esse livro foi originalmente publicado como uma edi\u00e7\u00e3o de presente para os amigos de Mary Baker Eddy, os quais a encorajaram a torn\u00e1-lo p\u00fablico. Cont\u00e9m 48 poemas originais escritos ao longo de sua vida, a come\u00e7ar da inf\u00e2ncia. Sete deles foram musicados e fazem parte do <em>Hin\u00e1rio da Ci\u00eancia Crist\u00e3<\/em>.<\/span><\/p>\n<h3><span style=\"font-weight: 600;\"><i>The First Church of Christ, Scientist, and Miscellany <\/i>[A Primeira Igreja de Cristo, Cientista, e Outros Textos] (1913)\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Mary Baker Eddy compilou e editou esse livro de duas partes. A Parte I (\u201cA Primeira Igreja de Cristo, Cientista\u201d) descreve a constru\u00e7\u00e3o da Extens\u00e3o da Igreja M\u00e3e em Boston. Escritos da Sra. Eddy, bem como artigos de jornais de toda a Am\u00e9rica do Norte, detalham essa importante conquista arquitet\u00f4nica e o desenvolvimento do movimento da Ci\u00eancia Crist\u00e3. A Parte II (\u201coutros Textos\u201d) consiste em mensagens que a Sra. Eddy escreveu para apoiar e encorajar sua igreja.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Mary Baker Eddy era uma pensadora e escritora ativa. Ela se dedicava ao discurso com milhares de homens e mulheres, incluindo alguns l\u00edderes de pensamento estabelecidos. As obras publicadas da Sra. Eddy desafiaram abertamente o pensamento convencional em teologia, medicina e ci\u00eancia.<\/p>","protected":false},"author":6,"featured_media":0,"parent":49376,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"class_list":["post-49329","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Writings- Os escritos de Mary Baker Eddy<\/title>\n<meta name=\"description\" content=\"Os escritos de Mary Baker Eddy desafiaram abertamente o pensamento convencional em teologia, medicina e ci\u00eancia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Writings- Os escritos de Mary Baker Eddy\" \/>\n<meta property=\"og:description\" content=\"Os escritos de Mary Baker Eddy desafiaram abertamente o pensamento convencional em teologia, medicina e ci\u00eancia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/\" \/>\n<meta property=\"og:site_name\" content=\"A Biblioteca Mary Baker Eddy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mbelibrary\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-02T15:39:34+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/mary-baker-eddy\\\/escritos\\\/\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/mary-baker-eddy\\\/escritos\\\/\",\"name\":\"Writings- Os escritos de Mary Baker Eddy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#website\"},\"datePublished\":\"2022-07-25T19:44:37+00:00\",\"dateModified\":\"2022-09-02T15:39:34+00:00\",\"description\":\"Os escritos de Mary Baker Eddy desafiaram abertamente o pensamento convencional em teologia, medicina e ci\u00eancia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/mary-baker-eddy\\\/escritos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/mary-baker-eddy\\\/escritos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/mary-baker-eddy\\\/escritos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mary Baker Eddy\",\"item\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/mary-baker-eddy\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Escritos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/\",\"name\":\"A Biblioteca Mary Baker Eddy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#organization\",\"name\":\"The Mary Baker Eddy Library\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/MBEL_logo_HR.jpg\",\"contentUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/MBEL_logo_HR.jpg\",\"width\":2100,\"height\":2100,\"caption\":\"The Mary Baker Eddy Library\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mbelibrary\",\"https:\\\/\\\/x.com\\\/mbelibrary\",\"https:\\\/\\\/www.instagram.com\\\/mbelibrary\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Writings- Os escritos de Mary Baker Eddy","description":"Os escritos de Mary Baker Eddy desafiaram abertamente o pensamento convencional em teologia, medicina e ci\u00eancia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/","og_locale":"pt_BR","og_type":"article","og_title":"Writings- Os escritos de Mary Baker Eddy","og_description":"Os escritos de Mary Baker Eddy desafiaram abertamente o pensamento convencional em teologia, medicina e ci\u00eancia.","og_url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/","og_site_name":"A Biblioteca Mary Baker Eddy","article_publisher":"https:\/\/www.facebook.com\/mbelibrary","article_modified_time":"2022-09-02T15:39:34+00:00","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/","url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/","name":"Writings- Os escritos de Mary Baker Eddy","isPartOf":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#website"},"datePublished":"2022-07-25T19:44:37+00:00","dateModified":"2022-09-02T15:39:34+00:00","description":"Os escritos de Mary Baker Eddy desafiaram abertamente o pensamento convencional em teologia, medicina e ci\u00eancia.","breadcrumb":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/escritos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marybakereddylibrary.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Mary Baker Eddy","item":"https:\/\/www.marybakereddylibrary.org\/pt-br\/mary-baker-eddy\/"},{"@type":"ListItem","position":3,"name":"Escritos"}]},{"@type":"WebSite","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#website","url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/","name":"A Biblioteca Mary Baker Eddy","description":"","publisher":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marybakereddylibrary.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#organization","name":"The Mary Baker Eddy Library","url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2015\/03\/MBEL_logo_HR.jpg","contentUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2015\/03\/MBEL_logo_HR.jpg","width":2100,"height":2100,"caption":"The Mary Baker Eddy Library"},"image":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mbelibrary","https:\/\/x.com\/mbelibrary","https:\/\/www.instagram.com\/mbelibrary"]}]}},"_links":{"self":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/pages\/49329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/comments?post=49329"}],"version-history":[{"count":0,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/pages\/49329\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/pages\/49376"}],"wp:attachment":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/media?parent=49329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}