{"id":36271,"date":"2021-05-05T08:01:23","date_gmt":"2021-05-05T12:01:23","guid":{"rendered":"https:\/\/www.marybakereddylibrary.org\/?p=36271"},"modified":"2022-04-21T13:26:40","modified_gmt":"2022-04-21T17:26:40","slug":"como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia","status":"publish","type":"post","link":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/","title":{"rendered":"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia?"},"content":{"rendered":"<div id=\"modal-ready\"><p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;3.22&#8243;][et_pb_fullwidth_post_title author=&#8221;off&#8221; date_format=&#8221;j F Y&#8221; categories=&#8221;off&#8221; comments=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;3.29.3&#8243; z_index_tablet=&#8221;500&#8243; title_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; title_text_shadow_vertical_length_tablet=&#8221;0px&#8221; title_text_shadow_blur_strength_tablet=&#8221;1px&#8221; meta_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; meta_text_shadow_vertical_length_tablet=&#8221;0px&#8221; meta_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_shadow_blur_strength_tablet=&#8221;1px&#8221;][\/et_pb_fullwidth_post_title][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;3.0.47&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2021\/02\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg&#8221; alt=&#8221;Eddy&#8217;s house in Lynn, MA&#8221; title_text=&#8221;AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px&#8221; _builder_version=&#8221;4.6.6&#8243; z_index_tablet=&#8221;500&#8243; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.6.6&#8243;]<\/p>\n<p class=\"custom-caption-centered\">Esquina das Ruas Market e Oxford, Lynn, Massachusetts, c. 1871. P07176. Fot\u00f3grafo desconhecido.<\/p>\n<p>Cinco meses antes de falecer, Mary Baker Eddy comentou: \u201cO la\u00e7o mais forte que sempre tive, al\u00e9m do amor de Deus, foi o meu amor pelo lar\u201d.<span id='easy-footnote-1-36271' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#easy-footnote-bottom-1-36271' title='Ver Reminiscence File [Arquivo de Reminisc\u00eancias], di\u00e1rio de William Rathvon, anota\u00e7\u00e3o de 3 de julho de 1910.'><sup>1<\/sup><\/a><\/span> Durante sua longa vida, ela viveu em muitos locais, em condi\u00e7\u00f5es variadas, por per\u00edodos curtos e longos. Houve per\u00edodos em que sua situa\u00e7\u00e3o poderia ser considerada prec\u00e1ria, em termos de moradia, e estima-se que ela tenha se mudado em torno de 70 vezes. Mas sempre foi importante para ela ter acomoda\u00e7\u00f5es nas quais estabelecer seu senso de lar, como \u201co lugar mais querido da terra\u201d e \u201co centro, mas n\u00e3o o limite, dos afetos\u201d.<span id='easy-footnote-2-36271' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#easy-footnote-bottom-2-36271' title='Mary Baker Eddy, &lt;em&gt;Ci\u00eancia e Sa\u00fade com a Chave das Escrituras&lt;\/em&gt; (Boston: The Christian Science Board of Directors), 58.'><sup>2<\/sup><\/a><\/span><\/p>\n<p>Em sua busca por uma moradia est\u00e1vel, a Sra. Eddy encontrou desafios, especialmente entre os anos de 1844 e 1875. Na inf\u00e2ncia e adolesc\u00eancia, ela morou em duas casas que eram de seu pai, Mark Baker. A fam\u00edlia primeiro morou em uma fazenda em Bow, New Hampshire, desde o nascimento de Mary, em 1821, at\u00e9 1836, quando se mudou para a cidadezinha de Sanbornton Bridge (que mais tarde passou a se chamar Tilton).<\/p>\n<p>Quando a Sra. Eddy se casou com George Washington Glover, em 1843, parecia que seu marido, um empreiteiro, continuaria a propiciar-lhe uma casa confort\u00e1vel. Mudaram-se para a Carolina do Sul em 1844. Mas depois de apenas seis meses, George Glover morreu, e sua esposa vi\u00fava e gr\u00e1vida voltou para a casa dos pais. Mais de trinta anos de dificuldades se seguiram, durante os quais ela lutou para encontrar locais adequados e mais est\u00e1veis para morar. Esses anos de instabilidade chegaram ao fim em 1875, com a compra de uma casa na Rua Broad, 8, em Lynn, Massachusetts.<\/p>\n<p>Em nenhuma circunst\u00e2ncia a Sra. Eddy precisou viver nas ruas, durante esses anos; os lugares para morar sempre se abriram para ela, embora com frequ\u00eancia deixassem muito a desejar. \u00c0s vezes, ela morou com parentes, e em determinado momento, morou em uma casa de propriedade de sua irm\u00e3, Martha Pilsbury. Durante um per\u00edodo, mudou-se frequentemente entre uma s\u00e9rie de pens\u00f5es e resid\u00eancias particulares, de propriedade de outras pessoas. De acordo com o bi\u00f3grafo Robert Peel: \u201cPor toda a sua vida, ter uma casa pr\u00f3pria foi uma quest\u00e3o da mais alta import\u00e2ncia para a Sra. Eddy, e uma de suas maiores dificuldades foi justamente o fato de que em grande parte de sua exist\u00eancia precisou morar na casa de outras pessoas\u201d.<span id='easy-footnote-3-36271' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#easy-footnote-bottom-3-36271' title='Robert Peel, &lt;em&gt;Mary Baker Eddy: The Years of Discovery&lt;\/em&gt; [Mary Baker Eddy: Os anos da descoberta] (Boston: The Christian Science Publishing Society, 1966), 140.'><sup>3<\/sup><\/a><\/span><\/p>\n<p>Um exemplo dos problemas da Sra. Eddy, quanto a morar com parentes, ocorreu quando ela e seu filho pequeno, George Glover II, n\u00e3o puderam mais morar na casa do pai de Mary, depois de este ter se casado de novo em 1850, ap\u00f3s ter ficado vi\u00favo um ano antes. Em 1851, ela foi morar com a irm\u00e3, Abigail Baker Tilton, com quem permaneceu por dois anos. Tilton achava que George era dif\u00edcil de ser controlado e tamb\u00e9m passou a acreditar que, devido ao fato de Mary ficar constantemente doente, sua irm\u00e3 ficaria melhor sem precisar cuidar do menino. Decidiram por ela que uma jovem chamada Mahala Sanborn passaria a cuidar da crian\u00e7a. Sanborn acabara de se casar com Russel Cheney, e o casal se mudou para o vilarejo remoto de North Groton, no sop\u00e9 das White Mountains de New Hampshire, levando George com eles.<\/p>\n<p>Em 1853, Mary se casou com o dentista Daniel Patterson e, no final de abril de 1855, eles tamb\u00e9m foram morar em North Groton \u2014 provavelmente devido ao forte desejo dela de estar perto do filho, de quem sentia muita falta. Mas Daniel Patterson n\u00e3o permitiu que George morasse com eles e, um ano depois, os Cheneys se mudaram para Enterprise, Minnesota, a centenas de quil\u00f4metros de dist\u00e2ncia, levando George com eles. Depois disso, a sa\u00fade prec\u00e1ria de Mary Patterson se transformou em invalidez, e seu marido n\u00e3o ganhava o suficiente como dentista. Isso, juntamente com o p\u00e2nico financeiro nacional de 1857 e a depress\u00e3o econ\u00f4mica, acabaram por levar Pilsbury a executar a hipoteca que detinha sobre a propriedade de North Groton.<\/p>\n<p>Em 20 de setembro de 1859, Mary Patterson escreveu em seu caderno: \u201cNeste dia, minha irm\u00e3 vendeu a casa onde moramos\u201d (embora eles n\u00e3o tenham se mudado at\u00e9 mar\u00e7o do ano seguinte). Em seguida, escreveu um poema em que expressou sua ang\u00fastia:<\/p>\n<p style=\"padding-left: 30px;\">Pai, n\u00e3o viste a onda negra esmagadora,<br \/>Elevar do desespero aquele que luta contra o mar?<br \/>E n\u00e3o v\u00eas as l\u00e1grimas escaldantes que derramo,<br \/>E n\u00e3o conheces a minha dor e agonia? \u2026<br \/>Pois a minha alma enferma est\u00e1 na escurid\u00e3o da morte,<br \/>Com as terr\u00edveis sombras deste mundo de afli\u00e7\u00e3o;<br \/>Os fortes alicerces da minha antiga f\u00e9<br \/>Contraem-se sob mim, para onde fugirei?<br \/>Esconde-me, \u00f3 rocha santa! Escondo-me em Ti.<span id='easy-footnote-4-36271' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#easy-footnote-bottom-4-36271' title='Poema sem t\u00edtulo, Caderno n&lt;sup&gt;o&lt;\/sup&gt; 1, anota\u00e7\u00e3o do dia 20 de setembro de 1859, A09001, 60\u201361.'><sup>4<\/sup><\/a><\/span><\/p>\n<p>Os Pattersons foram para uma pens\u00e3o em Rumney Depot, New Hampshire. Nos 15 anos seguintes, pens\u00f5es e quartos alugados em casas particulares seriam os principais locais em que Mary Patterson morou. Nessa \u00e9poca, era comum as mulheres administrarem pens\u00f5es e alugar quartos, como forma de obter renda extra. Ela passou a maior parte desses anos sozinha; seu marido viajava com frequ\u00eancia, foi capturado e preso durante a Guerra Civil, e a abandonou na primavera de 1866. Por fim, Mary se divorciou dele em 1873.<\/p>\n<p>Sua situa\u00e7\u00e3o de moradia era inst\u00e1vel. Por exemplo, no outono de 1867, ela se mudou para o vilarejo de Amesbury, Massachusetts, onde encontrou hospedagem e alimenta\u00e7\u00e3o em uma grande casa, de propriedade de um capit\u00e3o aposentado, Nathaniel Webster. Sua esposa, conhecida como \u201cM\u00e3e Webster\u201d, administrava a casa como se fosse uma pens\u00e3o. Quando Mary disse a M\u00e3e Webster que se sentira impelida a solicitar hospedagem ali, ela exclamou: \u201cGl\u00f3ria a Deus, entre imediatamente!\u201d<span id='easy-footnote-5-36271' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#easy-footnote-bottom-5-36271' title='Declara\u00e7\u00e3o de Mary Ellis Bartlett, citada no livro de Georgine Milmine, &lt;em&gt;The Life of Mary Baker G. Eddy and the History of Christian Science&lt;\/em&gt; [A vida de Mary Baker Eddy e a hist\u00f3ria da Ci\u00eancia Crist\u00e3] (New York: Doubleday, Page, &amp;amp; Co., 1909), 116.'><sup>5<\/sup><\/a><\/span><\/p>\n<p>Mas sua perman\u00eancia na casa dos Websters durou cerca de dez meses, apenas. Antes que os netos de Webster chegarem, cada ver\u00e3o, os h\u00f3spedes eram sumariamente despejados. E em uma noite de tempestade, a Sra. Eddy, junto com seus poucos pertences, foi expulsa da casa. Naquele momento, um colega da pens\u00e3o a acompanhou e, descendo a rua, ela encontrou imediatamente um novo alojamento na resid\u00eancia de Sarah Bagley, que se tornaria uma das primeiras alunas da pesquisa b\u00edblica que consumia todo o tempo e aten\u00e7\u00e3o de Mary.<\/p>\n<p><em>Ci\u00eancia e Sa\u00fade<\/em> foi publicado em outubro de 1875. No in\u00edcio daquele ano \u2014 novamente usando seu antigo nome, Mary Glover (ela s\u00f3 se tornaria Mary Baker Eddy em seu casamento com Asa Gilbert Eddy, em 1877) \u2014 j\u00e1 estava morando em outra casa, em Lynn. Num dia de mar\u00e7o, ela olhou pela janela e viu que a casa do outro lado da rua estava \u00e0 venda. No final do m\u00eas, ela comprou a casa.<\/p>\n<p>Nessa altura, a situa\u00e7\u00e3o mudou em certo sentido \u2014 era ela agora a mulher que alugava quartos para outras pessoas, reservando apenas uma pequena parte da casa para si mesma. A compra da casa na Rua Broad, 8, marcou o fim de seus anos de instabilidade no que concerne \u00e0 moradia. Como sua renda aumentou, depois do ano de 1875, com a venda de seus escritos, bem como com a renda dos alugu\u00e9is, ela passou a ter condi\u00e7\u00f5es de pagar por acomoda\u00e7\u00f5es mais adequadas. Seu amor pelo lar e pela fam\u00edlia acabaria se ampliando, de modo a incluir uma casa com funcion\u00e1rios que, al\u00e9m de morar com ela, ajudaram em seu trabalho de lideran\u00e7a do movimento da Ci\u00eancia Crist\u00e3.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.0.47&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_sidebar orientation=&#8221;right&#8221; area=&#8221;et_pb_widget_area_3&#8243; _builder_version=&#8221;3.7.1&#8243;][\/et_pb_sidebar][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Leia sobre as v\u00e1rias d\u00e9cadas em que a fundadora da Ci\u00eancia Crist\u00e3 enfrentou e venceu o desafio de ter um teto para se abrigar.<\/p>","protected":false},"author":44,"featured_media":35033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"2normal","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[184],"tags":[],"class_list":["post-36271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pergunte-a-um-pesquisador"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia? - A Biblioteca Mary Baker Eddy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia? - A Biblioteca Mary Baker Eddy\" \/>\n<meta property=\"og:description\" content=\"Leia sobre as v\u00e1rias d\u00e9cadas em que a fundadora da Ci\u00eancia Crist\u00e3 enfrentou e venceu o desafio de ter um teto para se abrigar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/\" \/>\n<meta property=\"og:site_name\" content=\"A Biblioteca Mary Baker Eddy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mbelibrary\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-05T12:01:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-21T17:26:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2021\/02\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"The Mary Baker Eddy Library\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"The Mary Baker Eddy Library\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/\"},\"author\":{\"name\":\"The Mary Baker Eddy Library\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/82abfd938c00bb8542667a796d4e449a\"},\"headline\":\"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia?\",\"datePublished\":\"2021-05-05T12:01:23+00:00\",\"dateModified\":\"2022-04-21T17:26:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/\"},\"wordCount\":1671,\"publisher\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg\",\"articleSection\":[\"Pergunte a um pesquisador\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/\",\"name\":\"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia? - A Biblioteca Mary Baker Eddy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg\",\"datePublished\":\"2021-05-05T12:01:23+00:00\",\"dateModified\":\"2022-04-21T17:26:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg\",\"width\":800,\"height\":500,\"caption\":\"Eddy's house in Lynn, MA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/research\\\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/\",\"name\":\"A Biblioteca Mary Baker Eddy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#organization\",\"name\":\"The Mary Baker Eddy Library\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/MBEL_logo_HR.jpg\",\"contentUrl\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/MBEL_logo_HR.jpg\",\"width\":2100,\"height\":2100,\"caption\":\"The Mary Baker Eddy Library\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mbelibrary\",\"https:\\\/\\\/x.com\\\/mbelibrary\",\"https:\\\/\\\/www.instagram.com\\\/mbelibrary\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marybakereddylibrary.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/82abfd938c00bb8542667a796d4e449a\",\"name\":\"The Mary Baker Eddy Library\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/47a742fb4f6cc6ad0d0564fe6349235105346e31e12bacfbe4c85164ba549b72?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/47a742fb4f6cc6ad0d0564fe6349235105346e31e12bacfbe4c85164ba549b72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/47a742fb4f6cc6ad0d0564fe6349235105346e31e12bacfbe4c85164ba549b72?s=96&d=mm&r=g\",\"caption\":\"The Mary Baker Eddy Library\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia? - A Biblioteca Mary Baker Eddy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/","og_locale":"pt_BR","og_type":"article","og_title":"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia? - A Biblioteca Mary Baker Eddy","og_description":"Leia sobre as v\u00e1rias d\u00e9cadas em que a fundadora da Ci\u00eancia Crist\u00e3 enfrentou e venceu o desafio de ter um teto para se abrigar.","og_url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/","og_site_name":"A Biblioteca Mary Baker Eddy","article_publisher":"https:\/\/www.facebook.com\/mbelibrary","article_published_time":"2021-05-05T12:01:23+00:00","article_modified_time":"2022-04-21T17:26:40+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2021\/02\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg","type":"image\/jpeg"}],"author":"The Mary Baker Eddy Library","twitter_misc":{"Escrito por":"The Mary Baker Eddy Library","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#article","isPartOf":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/"},"author":{"name":"The Mary Baker Eddy Library","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#\/schema\/person\/82abfd938c00bb8542667a796d4e449a"},"headline":"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia?","datePublished":"2021-05-05T12:01:23+00:00","dateModified":"2022-04-21T17:26:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/"},"wordCount":1671,"publisher":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#organization"},"image":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2021\/02\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg","articleSection":["Pergunte a um pesquisador"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/","url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/","name":"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia? - A Biblioteca Mary Baker Eddy","isPartOf":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#primaryimage"},"image":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2021\/02\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg","datePublished":"2021-05-05T12:01:23+00:00","dateModified":"2022-04-21T17:26:40+00:00","breadcrumb":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#primaryimage","url":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2021\/02\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg","contentUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2021\/02\/AaR-Article-Eddy-face-housing-insecurity-P07176_800x500px.jpg","width":800,"height":500,"caption":"Eddy's house in Lynn, MA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/research\/como-mary-baker-eddy-enfrentou-a-inseguranca-quanto-a-moradia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marybakereddylibrary.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Como Mary Baker Eddy enfrentou a inseguran\u00e7a quanto \u00e0 moradia?"}]},{"@type":"WebSite","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#website","url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/","name":"A Biblioteca Mary Baker Eddy","description":"","publisher":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marybakereddylibrary.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#organization","name":"The Mary Baker Eddy Library","url":"https:\/\/www.marybakereddylibrary.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2015\/03\/MBEL_logo_HR.jpg","contentUrl":"https:\/\/www.marybakereddylibrary.org\/wp-content\/uploads\/2015\/03\/MBEL_logo_HR.jpg","width":2100,"height":2100,"caption":"The Mary Baker Eddy Library"},"image":{"@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mbelibrary","https:\/\/x.com\/mbelibrary","https:\/\/www.instagram.com\/mbelibrary"]},{"@type":"Person","@id":"https:\/\/www.marybakereddylibrary.org\/pt-br\/#\/schema\/person\/82abfd938c00bb8542667a796d4e449a","name":"The Mary Baker Eddy Library","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/47a742fb4f6cc6ad0d0564fe6349235105346e31e12bacfbe4c85164ba549b72?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/47a742fb4f6cc6ad0d0564fe6349235105346e31e12bacfbe4c85164ba549b72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/47a742fb4f6cc6ad0d0564fe6349235105346e31e12bacfbe4c85164ba549b72?s=96&d=mm&r=g","caption":"The Mary Baker Eddy Library"}}]}},"_links":{"self":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/posts\/36271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/comments?post=36271"}],"version-history":[{"count":0,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/posts\/36271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/media\/35033"}],"wp:attachment":[{"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/media?parent=36271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/categories?post=36271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marybakereddylibrary.org\/pt-br\/wp-json\/wp\/v2\/tags?post=36271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}